{"id":1407,"date":"2013-02-27T11:35:00","date_gmt":"2013-02-27T10:35:00","guid":{"rendered":"https:\/\/gestiobcn.com\/?p=1407"},"modified":"2019-04-15T14:50:12","modified_gmt":"2019-04-15T13:50:12","slug":"nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas","status":"publish","type":"post","link":"https:\/\/gestiobcn.com\/es\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\/","title":{"rendered":"Nuevos incentivos a la contrataci\u00f3n para aut\u00f3nomos y empresas"},"content":{"rendered":"<p align=\"center\"><span style=\"color: #ffffff;\">. <\/span><\/p>\n<p style=\"text-align: center;\" align=\"center\"><span style=\"color: #333333;\"><strong>El pasado s\u00e1bado 23 de febrero de 2013, fue publicado el <em><span style=\"text-decoration: underline;\"><a style=\"color: #333333; text-decoration: underline;\" href=\"http:\/\/www.boe.es\/boe\/dias\/2013\/02\/23\/pdfs\/BOE-A-2013-2030.pdf\">Real Decreto Ley 4\/2013, de medidas de apoyo al emprendedor y de est\u00edmulo del crecimiento y de la creaci\u00f3n de empleo.<\/a><\/span><\/em><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #333333;\"><strong>El RDL establece un nuevo plan de pago para las Administraciones P\u00fablicas, regula inversiones en el Mercado Alternativo Burs\u00e1til, establece la liberalizaci\u00f3n del mercado ferroviario y adem\u00e1s, haciendo gala a su t\u00edtulo, establece medidas orientadas a la creaci\u00f3n de empleo.<\/strong><\/span><\/p>\n<p style=\"text-align: center;\" align=\"center\"><span style=\"color: #333333;\"><strong>Encontramos en el T\u00edtulo I y divididas en los tres primeros cap\u00edtulos, una serie de medidas de incentivos sociales, fiscales y en la contrataci\u00f3n.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">En este primer resumen de la norma nos centramos en el cap\u00edtulo III el cual,\u00a0toma medidas destinadas \u00a0<strong><em>a incentivar la incorporaci\u00f3n de los j\u00f3venes a las empresas de Econom\u00eda Social, as\u00ed como est\u00edmulos a la contrataci\u00f3n de j\u00f3venes en situaci\u00f3n de desempleo. <\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Estas medidas son:<\/p>\n<ul style=\"list-style-type: square;\">\n<li><strong><span style=\"color: #808000;\">INCENTIVOS A LA CONTRATACI\u00d3N A TIEMPO PARCIAL CON VINCULACI\u00d3N FORMATIVA:<\/span><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Las empresas, incluidos los trabajadores aut\u00f3nomos, que realicen \u00a0<strong>contratos a tiempo parcial con vinculaci\u00f3n formativa<\/strong> para <strong>desempleados menores de 30 a\u00f1os<\/strong> tendr\u00e1n derecho, durante un m\u00e1ximo de <strong>12 meses<\/strong>, a una reducci\u00f3n de la cuota empresarial a la Seguridad Social por contingencias comunes del 100%, si su plantilla es inferior a 250 personas, o del 75% si la plantilla fuese igual o superior.<\/p>\n<p style=\"text-align: justify;\">Los trabajadores deben cumplir alguno de los siguientes requisitos:<\/p>\n<ol>\n<li>No tener experiencia laboral previa o que la misma sea inferior a tres meses.<\/li>\n<li>Proceder de otro sector de actividad.<\/li>\n<li>Ser desempleado y estar inscrito ininterrumpidamente en la oficina de empleo durante al menos doce meses en el per\u00edodo de 18 meses anteriores a la contrataci\u00f3n.<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Los trabajadores deber\u00e1n compatibilizar el empleo con la formaci\u00f3n o justificar haberla recibido en los seis meses previos a la celebraci\u00f3n del contrato. <span style=\"text-decoration: underline;\">Cabe la posibilidad de que la formaci\u00f3n no est\u00e9 vinculada al puesto de trabajo<\/span> objeto del empleo y ser\u00e1 formaci\u00f3n \u00a0acreditable oficial o promovida por los Servicios P\u00fablicos de Empleo, o bien formaci\u00f3n en idiomas o en tecnolog\u00edas de la informaci\u00f3n y la comunicaci\u00f3n de una duraci\u00f3n m\u00ednima de 90 horas en c\u00f3mputo anual.<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\">El contrato podr\u00e1 ser indefinido o de duraci\u00f3n determinada<\/span>, y se pactar\u00e1 una jornada no superior al 50% de la correspondiente a un trabajador a tiempo completo.<\/p>\n<p style=\"text-align: justify;\">Para aplicar este beneficio<span style=\"text-decoration: underline;\">, la empresa ha de mantener el nivel de empleo alcanzado con este contrato durante toda la duraci\u00f3n del mismo con un m\u00e1ximo de doce meses<\/span> desde su celebraci\u00f3n, salvo despido por causas objetivas y despido disciplinario, ambos procedentes, y extinci\u00f3n de la relaci\u00f3n laboral por dimisi\u00f3n, muerte, jubilaci\u00f3n o incapacidad permanente total, absoluta o gran invalidez de los trabajadores o por haber expirado el tiempo convenido o realizaci\u00f3n de la obra o servicio objeto del contrato, o por resoluci\u00f3n durante el per\u00edodo de prueba. Y deben contemplarse los supuesto de exclusi\u00f3n de la norma.<\/p>\n<p>&nbsp;<\/p>\n<ul style=\"list-style-type: square;\">\n<li><strong><span style=\"color: #808000;\">CONTRATACI\u00d3N INDEFINIDA DE UNA JOVEN POR MICROEMPRESAS Y EMPRESARIOS AUT\u00d3NOMOS:<\/span><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Las empresas, incluidos trabajadores aut\u00f3nomos <strong>con menos de nueve trabajadores<\/strong> que cumplan todos los requisitos del Art. 10\u00a0 <a href=\"http:\/\/www.boe.es\/boe\/dias\/2013\/02\/23\/pdfs\/BOE-A-2013-2030.pdf\">VER AQU\u00cd<\/a>,\u00a0al contratar a un <strong>menor de 30 a\u00f1os desempleado<\/strong> mediante <strong>contrato indefinido<\/strong> a tiempo <strong>completo o parcial<\/strong>, podr\u00e1n aplicarse una bonificaci\u00f3n del 100% de la cuota empresarial por contingencias comunes <strong>durante el primer a\u00f1o<\/strong> del contrato.<\/p>\n<p style=\"text-align: justify;\">Para aplicar la bonificaci\u00f3n, la empresa debe <span style=\"text-decoration: underline;\">mantener al trabajador al menos durante 18 meses <\/span>desde la fecha de inicio de la relaci\u00f3n laboral, salvo que el contrato se extinga por causa no imputable al empresario o por resoluci\u00f3n durante el per\u00edodo de prueba. Adem\u00e1s deber\u00e1 mantener el nivel de empleo alcanzado con el contrato durante al menos un a\u00f1o, salvo que se produzca despido por causas objetivas y despido disciplinario, ambos procedentes, y extinci\u00f3n de la relaci\u00f3n laboral por dimisi\u00f3n, muerte, jubilaci\u00f3n o incapacidad permanente total, absoluta o gran invalidez de los trabajadores o por haber expirado el tiempo convenido o realizaci\u00f3n de la obra o servicio objeto del contrato, o por resoluci\u00f3n durante el per\u00edodo de prueba. En este \u00faltimo caso, podr\u00e1 celebrarse un nuevo contrato de esta modalidad, hasta computar los doce meses de bonificaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<ul style=\"list-style-type: square;\">\n<li><strong><span style=\"color: #808000;\">INCENTIVOS A LA CONTRATACI\u00d3N EN NUEVOS PROYECTOS DE EMPRENDIMIENTO JOVEN:<\/span><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Reducci\u00f3n del 100% de la cuota empresarial a la Seguridad Social <strong>durante 12 meses<\/strong> los <strong>trabajadores aut\u00f3nomos sin trabajadores y menores de 30 a\u00f1os<\/strong> que contraten por primera vez, de <strong>forma indefinida<\/strong> ya sea jornada completa o parcial a personas <strong>desempleadas mayores de 45 a\u00f1os<\/strong> e inscritas en la oficina de empleo durante doce meses en los dieciocho meses anteriores a la contrataci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Deber\u00e1 mantenerse el empleo al trabajador contratado al menos, dieciocho meses.<\/p>\n<p>&nbsp;<\/p>\n<ul style=\"list-style-type: square;\">\n<li><strong><span style=\"color: #808000;\">PRIMER EMPLEO JOVEN:<\/span><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Las empresas que contraten a <strong>j\u00f3venes menores de 30 a\u00f1os<\/strong>, sin experiencia laboral (o menor a tres meses), mediante jornada completa o parcial y <strong>contrato temporal<\/strong>&#8211; no inferior a tres meses, ni superior a seis- <strong>y transformen el contrato a indefinido<\/strong> antes de tres meses, podr\u00e1n acogerse a la siguientes bonificaciones en las cuotas empresariales a la Seguridad Social:<\/p>\n<ol>\n<li>41,67 euros\/mes (500 euros\/a\u00f1o) durante tres a\u00f1os, siempre que la jornada pactada sea al menos del 50% de la correspondiente a un trabajador a tiempo completo.<\/li>\n<li>\u00a0Si el contrato se celebrase con una mujer, la bonificaci\u00f3n ser\u00e1 de 58,33 euros\/mes (700 euros\/a\u00f1o).<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ul style=\"list-style-type: square;\">\n<li><strong><span style=\"color: #808000;\">INCENTIVOS A LOS CONTRATOS EN PR\u00c1CTICAS PARA EL PRIMER EMPLEO:<\/span><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Las empresas, incluidos trabajadores aut\u00f3nomos, que realicen <strong>contratos en pr\u00e1cticas<\/strong> a <strong>menores de 30 a\u00f1os<\/strong>&#8211; aunque hayan transcurrido m\u00e1s de cinco desde la terminaci\u00f3n los estudios-, tienen derecho a una reducci\u00f3n del 50% de la cuota empresarial a la Seguridad Social por contingencias comunes durante toda la vigencia del contrato.<\/p>\n<p>&nbsp;<\/p>\n<ul style=\"list-style-type: square;\">\n<li><strong><span style=\"color: #808000;\">INCENTIVOS A LA INCORPORACI\u00d3N DE J\u00d3VENES A ENTIDADES DE ECONOM\u00cdA SOCIAL:<\/span><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Podr\u00e1n aplicar una bonificaci\u00f3n en las cuotas empresariales a la Seguridad Social de 800 euros\/a\u00f1o, durante tres a\u00f1os aquellas <strong>cooperativas y sociedades laborales<\/strong> que contraten trabajadores <strong>desempleados menores de 30 a\u00f1os<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n podr\u00e1n acceder a una bonificaci\u00f3n en las cuotas de la Seguridad Social de 1.650 euros\/a\u00f1o durante la vigencia del contrato, o durante tres a\u00f1os, las <strong>empresas de inserci\u00f3n<\/strong>\u00a0 que contraten trabajadores <strong>menores de 30 a\u00f1os en situaci\u00f3n de exclusi\u00f3n social.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #808000;\"><strong>Asesor\u00eda en Barcelona<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #808000;\"><strong>SAGARRA I MONTALVO GESTI\u00d3 BCN<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><span style=\"color: #3366ff;\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>. El pasado s\u00e1bado 23 de febrero de 2013, fue publicado el Real Decreto Ley 4\/2013, de medidas de apoyo al emprendedor y de est\u00edmulo del crecimiento y de la&#8230;<\/p>\n","protected":false},"author":2,"featured_media":8934,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[182,38],"tags":[],"class_list":["post-1407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-laboral","category-sin-categorizar"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Nuevos incentivos aprobados para la contrataci\u00f3n por parte de aut\u00f3nomos y empresas. RDL 4\/2013\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"gestiobcn.com\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/gestiobcn.com\/es\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\\\/#article\",\"name\":\"Incentivos a la contrataci\\u00f3n | Assessoria SM Gesti\\u00f3 (Barcelona) Fiscal, laboral\",\"headline\":\"Nuevos incentivos a la contrataci\\u00f3n para aut\\u00f3nomos y empresas\",\"author\":{\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/author\\\/gestiobcn-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/gestiobcn.com\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/notprov0002211.jpg\",\"width\":400,\"height\":200},\"datePublished\":\"2013-02-27T11:35:00+01:00\",\"dateModified\":\"2019-04-15T14:50:12+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\\\/#webpage\"},\"articleSection\":\"Area Laboral, Sin categorizar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/category\\\/sin-categorizar\\\/#listItem\",\"name\":\"Sin categorizar\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/category\\\/sin-categorizar\\\/#listItem\",\"position\":2,\"name\":\"Sin categorizar\",\"item\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/category\\\/sin-categorizar\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\\\/#listItem\",\"name\":\"Nuevos incentivos a la contrataci\\u00f3n para aut\\u00f3nomos y empresas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\\\/#listItem\",\"position\":3,\"name\":\"Nuevos incentivos a la contrataci\\u00f3n para aut\\u00f3nomos y empresas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/category\\\/sin-categorizar\\\/#listItem\",\"name\":\"Sin categorizar\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/#organization\",\"name\":\"Sagarra i Montalvo Gesti\\u00f3 BCN SL\",\"description\":\"financial advisor\",\"url\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/\",\"telephone\":\"+34936673626\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/gestiobcn.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/fons-verd-quadrat.jpg\",\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\\\/#organizationLogo\",\"width\":280,\"height\":280,\"caption\":\"GestioBCN\"},\"image\":{\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/author\\\/gestiobcn-com\\\/#author\",\"url\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/author\\\/gestiobcn-com\\\/\",\"name\":\"gestiobcn.com\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/389a875dd476c929f14521a4296056fe4a02d1e911cd5457c7b036d4ae7dfba1?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"gestiobcn.com\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\\\/#webpage\",\"url\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\\\/\",\"name\":\"Incentivos a la contrataci\\u00f3n | Assessoria SM Gesti\\u00f3 (Barcelona) Fiscal, laboral\",\"description\":\"Nuevos incentivos aprobados para la contrataci\\u00f3n por parte de aut\\u00f3nomos y empresas. RDL 4\\\/2013\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/author\\\/gestiobcn-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/author\\\/gestiobcn-com\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/gestiobcn.com\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/notprov0002211.jpg\",\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\\\/#mainImage\",\"width\":400,\"height\":200},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\\\/#mainImage\"},\"datePublished\":\"2013-02-27T11:35:00+01:00\",\"dateModified\":\"2019-04-15T14:50:12+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/\",\"name\":\"Assessoria SM Gesti\\u00f3 (Barcelona) Fiscal, laboral\",\"description\":\"financial advisor\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/gestiobcn.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Incentivos a la contrataci\u00f3n | Assessoria SM Gesti\u00f3 (Barcelona) Fiscal, laboral","description":"Nuevos incentivos aprobados para la contrataci\u00f3n por parte de aut\u00f3nomos y empresas. RDL 4\/2013","canonical_url":"https:\/\/gestiobcn.com\/es\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gestiobcn.com\/es\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\/#article","name":"Incentivos a la contrataci\u00f3n | Assessoria SM Gesti\u00f3 (Barcelona) Fiscal, laboral","headline":"Nuevos incentivos a la contrataci\u00f3n para aut\u00f3nomos y empresas","author":{"@id":"https:\/\/gestiobcn.com\/es\/author\/gestiobcn-com\/#author"},"publisher":{"@id":"https:\/\/gestiobcn.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/gestiobcn.com\/wp-content\/uploads\/2013\/02\/notprov0002211.jpg","width":400,"height":200},"datePublished":"2013-02-27T11:35:00+01:00","dateModified":"2019-04-15T14:50:12+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/gestiobcn.com\/es\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\/#webpage"},"isPartOf":{"@id":"https:\/\/gestiobcn.com\/es\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\/#webpage"},"articleSection":"Area Laboral, Sin categorizar"},{"@type":"BreadcrumbList","@id":"https:\/\/gestiobcn.com\/es\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/gestiobcn.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/gestiobcn.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/gestiobcn.com\/es\/category\/sin-categorizar\/#listItem","name":"Sin categorizar"}},{"@type":"ListItem","@id":"https:\/\/gestiobcn.com\/es\/category\/sin-categorizar\/#listItem","position":2,"name":"Sin categorizar","item":"https:\/\/gestiobcn.com\/es\/category\/sin-categorizar\/","nextItem":{"@type":"ListItem","@id":"https:\/\/gestiobcn.com\/es\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\/#listItem","name":"Nuevos incentivos a la contrataci\u00f3n para aut\u00f3nomos y empresas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/gestiobcn.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/gestiobcn.com\/es\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\/#listItem","position":3,"name":"Nuevos incentivos a la contrataci\u00f3n para aut\u00f3nomos y empresas","previousItem":{"@type":"ListItem","@id":"https:\/\/gestiobcn.com\/es\/category\/sin-categorizar\/#listItem","name":"Sin categorizar"}}]},{"@type":"Organization","@id":"https:\/\/gestiobcn.com\/es\/#organization","name":"Sagarra i Montalvo Gesti\u00f3 BCN SL","description":"financial advisor","url":"https:\/\/gestiobcn.com\/es\/","telephone":"+34936673626","logo":{"@type":"ImageObject","url":"https:\/\/gestiobcn.com\/wp-content\/uploads\/2021\/04\/fons-verd-quadrat.jpg","@id":"https:\/\/gestiobcn.com\/es\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\/#organizationLogo","width":280,"height":280,"caption":"GestioBCN"},"image":{"@id":"https:\/\/gestiobcn.com\/es\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/gestiobcn.com\/es\/author\/gestiobcn-com\/#author","url":"https:\/\/gestiobcn.com\/es\/author\/gestiobcn-com\/","name":"gestiobcn.com","image":{"@type":"ImageObject","@id":"https:\/\/gestiobcn.com\/es\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/389a875dd476c929f14521a4296056fe4a02d1e911cd5457c7b036d4ae7dfba1?s=96&d=mm&r=g","width":96,"height":96,"caption":"gestiobcn.com"}},{"@type":"WebPage","@id":"https:\/\/gestiobcn.com\/es\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\/#webpage","url":"https:\/\/gestiobcn.com\/es\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\/","name":"Incentivos a la contrataci\u00f3n | Assessoria SM Gesti\u00f3 (Barcelona) Fiscal, laboral","description":"Nuevos incentivos aprobados para la contrataci\u00f3n por parte de aut\u00f3nomos y empresas. RDL 4\/2013","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/gestiobcn.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/gestiobcn.com\/es\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\/#breadcrumblist"},"author":{"@id":"https:\/\/gestiobcn.com\/es\/author\/gestiobcn-com\/#author"},"creator":{"@id":"https:\/\/gestiobcn.com\/es\/author\/gestiobcn-com\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/gestiobcn.com\/wp-content\/uploads\/2013\/02\/notprov0002211.jpg","@id":"https:\/\/gestiobcn.com\/es\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\/#mainImage","width":400,"height":200},"primaryImageOfPage":{"@id":"https:\/\/gestiobcn.com\/es\/nuevos-incentivos-a-la-contratacion-para-autonomos-y-empresas\/#mainImage"},"datePublished":"2013-02-27T11:35:00+01:00","dateModified":"2019-04-15T14:50:12+01:00"},{"@type":"WebSite","@id":"https:\/\/gestiobcn.com\/es\/#website","url":"https:\/\/gestiobcn.com\/es\/","name":"Assessoria SM Gesti\u00f3 (Barcelona) Fiscal, laboral","description":"financial advisor","inLanguage":"es-ES","publisher":{"@id":"https:\/\/gestiobcn.com\/es\/#organization"}}]}},"aioseo_meta_data":{"post_id":"1407","title":"Incentivos a la contrataci\u00f3n | #site_title","description":"Nuevos incentivos aprobados para la contrataci\u00f3n por parte de aut\u00f3nomos y empresas. RDL 4\/2013","keywords":[{"label":"asesor\u00eda Barcelona","value":"asesor\u00eda Barcelona"},{"label":"laboral","value":"laboral"},{"label":"bonificaciones","value":"bonificaciones"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-04-02 08:42:02","updated":"2025-11-20 04:14:53","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"_links":{"self":[{"href":"https:\/\/gestiobcn.com\/es\/wp-json\/wp\/v2\/posts\/1407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gestiobcn.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gestiobcn.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gestiobcn.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gestiobcn.com\/es\/wp-json\/wp\/v2\/comments?post=1407"}],"version-history":[{"count":0,"href":"https:\/\/gestiobcn.com\/es\/wp-json\/wp\/v2\/posts\/1407\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gestiobcn.com\/es\/wp-json\/wp\/v2\/media\/8934"}],"wp:attachment":[{"href":"https:\/\/gestiobcn.com\/es\/wp-json\/wp\/v2\/media?parent=1407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gestiobcn.com\/es\/wp-json\/wp\/v2\/categories?post=1407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gestiobcn.com\/es\/wp-json\/wp\/v2\/tags?post=1407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}